{"id":478675,"date":"2024-03-06T00:00:00","date_gmt":"2024-03-05T23:00:00","guid":{"rendered":"https:\/\/www.alfauna.ch\/shop\/unkategorisiert\/futterstation-mit-naepfen-heuraufe-holz\/"},"modified":"2026-07-16T00:45:19","modified_gmt":"2026-07-15T22:45:19","slug":"futterstation-mit-naepfen-heuraufe-holz","status":"publish","type":"product","link":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/","title":{"rendered":"Futterstation mit N\u00e4pfen\/Heuraufe, Holz"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":558081,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3597,2605],"product_tag":[],"class_list":{"0":"post-478675","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-naepfe-traenken-raufen","7":"product_cat-nagetiere-kaninchen","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Futterstation mit N\u00e4pfen\/Heuraufe, Holz - alfauna AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Futterstation mit N\u00e4pfen\/Heuraufe, Holz - alfauna AG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/\" \/>\n<meta property=\"og:site_name\" content=\"alfauna AG\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T22:45:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/2024\/04\/T61210_gr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/\",\"url\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/\",\"name\":\"Futterstation mit N\u00e4pfen\/Heuraufe, Holz - alfauna AG\",\"isPartOf\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/2024\/04\/T61210_gr.jpg\",\"datePublished\":\"2024-03-05T23:00:00+00:00\",\"dateModified\":\"2026-07-15T22:45:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/#primaryimage\",\"url\":\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/2024\/04\/T61210_gr.jpg\",\"contentUrl\":\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/2024\/04\/T61210_gr.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.alfauna.ch\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.alfauna.ch\/de\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Futterstation mit N\u00e4pfen\/Heuraufe, Holz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/#website\",\"url\":\"https:\/\/www.alfauna.ch\/de\/\",\"name\":\"alfauna AG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.alfauna.ch\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/#organization\",\"name\":\"alfauna AG\",\"url\":\"https:\/\/www.alfauna.ch\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/logo_alfauna_230px.png\",\"contentUrl\":\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/logo_alfauna_230px.png\",\"width\":230,\"height\":123,\"caption\":\"alfauna AG\"},\"image\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Futterstation mit N\u00e4pfen\/Heuraufe, Holz - alfauna AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/","og_locale":"de_DE","og_type":"article","og_title":"Futterstation mit N\u00e4pfen\/Heuraufe, Holz - alfauna AG","og_url":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/","og_site_name":"alfauna AG","article_modified_time":"2026-07-15T22:45:19+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/2024\/04\/T61210_gr.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/","url":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/","name":"Futterstation mit N\u00e4pfen\/Heuraufe, Holz - alfauna AG","isPartOf":{"@id":"https:\/\/www.alfauna.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/#primaryimage"},"image":{"@id":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/2024\/04\/T61210_gr.jpg","datePublished":"2024-03-05T23:00:00+00:00","dateModified":"2026-07-15T22:45:19+00:00","breadcrumb":{"@id":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/#primaryimage","url":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/2024\/04\/T61210_gr.jpg","contentUrl":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/2024\/04\/T61210_gr.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/naepfe-traenken-raufen\/futterstation-mit-naepfen-heuraufe-holz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.alfauna.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.alfauna.ch\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Futterstation mit N\u00e4pfen\/Heuraufe, Holz"}]},{"@type":"WebSite","@id":"https:\/\/www.alfauna.ch\/de\/#website","url":"https:\/\/www.alfauna.ch\/de\/","name":"alfauna AG","description":"","publisher":{"@id":"https:\/\/www.alfauna.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alfauna.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.alfauna.ch\/de\/#organization","name":"alfauna AG","url":"https:\/\/www.alfauna.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.alfauna.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/logo_alfauna_230px.png","contentUrl":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/logo_alfauna_230px.png","width":230,"height":123,"caption":"alfauna AG"},"image":{"@id":"https:\/\/www.alfauna.ch\/de\/#\/schema\/logo\/image\/"}}]}},"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"_links":{"self":[{"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/product\/478675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/media\/558081"}],"wp:attachment":[{"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/media?parent=478675"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/product_brand?post=478675"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/product_cat?post=478675"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/product_tag?post=478675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}