{"id":435146,"date":"2023-03-03T00:00:00","date_gmt":"2023-03-02T23:00:00","guid":{"rendered":"https:\/\/www.alfauna.ch\/shop\/unkategorisiert\/chipsi-clean-hanf-einstreu-f-kleintiere\/"},"modified":"2026-07-15T04:40:27","modified_gmt":"2026-07-15T02:40:27","slug":"chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg","status":"publish","type":"product","link":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/","title":{"rendered":"CHIPSI-Clean Hanf-Einstreu f. Kleintiere"},"content":{"rendered":"<p>Mit dem Hanf-Kleintierstreu Chipsi-Clean f&uuml;hlen sich Mensch und Tier wohl. Ein trockener Boden sorgt f&uuml;r Sauberkeit im Kleintierheim.&nbsp;<\/p>\n<p>Die nahezu staubfreien und sorgf&auml;ltig gereinigten Hanfteile sind hygienisch und f&uuml;r Allergiker geeignet.&nbsp;<\/p>\n<p>Der nachwachsende Rohstoff Hanf ist eine uralte Kulturpflanze und kann umweltfreundlich angebautwerden.&nbsp;<\/p>\n<p>100% biologisch abbaubar und kompostierbar.&nbsp;<\/p>\n<\/p>\n<p>Vorteile:&nbsp;<\/p>\n<p>Nahezu staubfrei.&nbsp;<\/p>\n<p>F&uuml;r Allergiker geeignet.&nbsp;<\/p>\n<p>Nachwachsender Rohstoff.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit dem Hanf-Kleintierstreu Chipsi-Clean f&uuml;hlen sich Mensch und Tier wohl. Ein trockener Boden sorgt f&uuml;r Sauberkeit im Kleintierheim.&nbsp; Die nahezu staubfreien und sorgf&auml;ltig gereinigten Hanfteile sind hygienisch und f&uuml;r Allergiker geeignet.&nbsp; Der nachwachsende Rohstoff Hanf ist eine uralte Kulturpflanze und kann umweltfreundlich angebautwerden.&nbsp; 100% biologisch abbaubar und kompostierbar.&nbsp; Vorteile:&nbsp; Nahezu staubfrei.&nbsp; F&uuml;r Allergiker geeignet.&nbsp; Nachwachsender<\/p>\n","protected":false},"featured_media":436616,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4073,2605],"product_tag":[],"class_list":{"0":"post-435146","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-toiletten-streu","7":"product_cat-nagetiere-kaninchen","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CHIPSI-Clean Hanf-Einstreu f. Kleintiere - alfauna AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHIPSI-Clean Hanf-Einstreu f. Kleintiere - alfauna AG\" \/>\n<meta property=\"og:description\" content=\"Mit dem Hanf-Kleintierstreu Chipsi-Clean f&uuml;hlen sich Mensch und Tier wohl. Ein trockener Boden sorgt f&uuml;r Sauberkeit im Kleintierheim.&nbsp; Die nahezu staubfreien und sorgf&auml;ltig gereinigten Hanfteile sind hygienisch und f&uuml;r Allergiker geeignet.&nbsp; Der nachwachsende Rohstoff Hanf ist eine uralte Kulturpflanze und kann umweltfreundlich angebautwerden.&nbsp; 100% biologisch abbaubar und kompostierbar.&nbsp; Vorteile:&nbsp; Nahezu staubfrei.&nbsp; F&uuml;r Allergiker geeignet.&nbsp; Nachwachsender\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/\" \/>\n<meta property=\"og:site_name\" content=\"alfauna AG\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T02:40:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/4241_gr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/\",\"url\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/\",\"name\":\"CHIPSI-Clean Hanf-Einstreu f. Kleintiere - alfauna AG\",\"isPartOf\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/4241_gr.jpg\",\"datePublished\":\"2023-03-02T23:00:00+00:00\",\"dateModified\":\"2026-07-15T02:40:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/#primaryimage\",\"url\":\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/4241_gr.jpg\",\"contentUrl\":\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/4241_gr.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.alfauna.ch\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.alfauna.ch\/de\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CHIPSI-Clean Hanf-Einstreu f. Kleintiere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/#website\",\"url\":\"https:\/\/www.alfauna.ch\/de\/\",\"name\":\"alfauna AG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.alfauna.ch\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/#organization\",\"name\":\"alfauna AG\",\"url\":\"https:\/\/www.alfauna.ch\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/logo_alfauna_230px.png\",\"contentUrl\":\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/logo_alfauna_230px.png\",\"width\":230,\"height\":123,\"caption\":\"alfauna AG\"},\"image\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHIPSI-Clean Hanf-Einstreu f. Kleintiere - alfauna AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/","og_locale":"de_DE","og_type":"article","og_title":"CHIPSI-Clean Hanf-Einstreu f. Kleintiere - alfauna AG","og_description":"Mit dem Hanf-Kleintierstreu Chipsi-Clean f&uuml;hlen sich Mensch und Tier wohl. Ein trockener Boden sorgt f&uuml;r Sauberkeit im Kleintierheim.&nbsp; Die nahezu staubfreien und sorgf&auml;ltig gereinigten Hanfteile sind hygienisch und f&uuml;r Allergiker geeignet.&nbsp; Der nachwachsende Rohstoff Hanf ist eine uralte Kulturpflanze und kann umweltfreundlich angebautwerden.&nbsp; 100% biologisch abbaubar und kompostierbar.&nbsp; Vorteile:&nbsp; Nahezu staubfrei.&nbsp; F&uuml;r Allergiker geeignet.&nbsp; Nachwachsender","og_url":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/","og_site_name":"alfauna AG","article_modified_time":"2026-07-15T02:40:27+00:00","og_image":[{"url":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/4241_gr.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/","url":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/","name":"CHIPSI-Clean Hanf-Einstreu f. Kleintiere - alfauna AG","isPartOf":{"@id":"https:\/\/www.alfauna.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/#primaryimage"},"image":{"@id":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/4241_gr.jpg","datePublished":"2023-03-02T23:00:00+00:00","dateModified":"2026-07-15T02:40:27+00:00","breadcrumb":{"@id":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/#primaryimage","url":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/4241_gr.jpg","contentUrl":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/4241_gr.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/toiletten-streu\/chipsi-clean-hanf-einstreu-f-kleintiere-30l-30kg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.alfauna.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.alfauna.ch\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"CHIPSI-Clean Hanf-Einstreu f. Kleintiere"}]},{"@type":"WebSite","@id":"https:\/\/www.alfauna.ch\/de\/#website","url":"https:\/\/www.alfauna.ch\/de\/","name":"alfauna AG","description":"","publisher":{"@id":"https:\/\/www.alfauna.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alfauna.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.alfauna.ch\/de\/#organization","name":"alfauna AG","url":"https:\/\/www.alfauna.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.alfauna.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/logo_alfauna_230px.png","contentUrl":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/logo_alfauna_230px.png","width":230,"height":123,"caption":"alfauna AG"},"image":{"@id":"https:\/\/www.alfauna.ch\/de\/#\/schema\/logo\/image\/"}}]}},"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":{"66":5.75},"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"_links":{"self":[{"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/product\/435146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/media\/436616"}],"wp:attachment":[{"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/media?parent=435146"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/product_brand?post=435146"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/product_cat?post=435146"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.alfauna.ch\/de\/wp-json\/wp\/v2\/product_tag?post=435146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}